{"id":873,"date":"2019-06-01T16:18:00","date_gmt":"2019-06-01T14:18:00","guid":{"rendered":"https:\/\/steuerportal.ch\/?post_type=sht_proarticle&#038;p=873"},"modified":"2019-11-25T12:21:53","modified_gmt":"2019-11-25T11:21:53","slug":"familienbesteuerung-vs-zivilstandbesteuerung","status":"publish","type":"sht_proarticle","link":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","title":{"rendered":"Familienbesteuerung vs. Zivilstandbesteuerung"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"<p>Liebe Leserinnen und Leser Am 28. Februar 2016 hat das Schweizer Stimmvolk &auml;usserst knapp die Volksinitiative &laquo;F&uuml;r Ehe und Familie &ndash; gegen die Heiratsstrafe&raquo; abgelehnt, welche die Diskriminierung von verheirateten Paaren und Paaren in eingetragener Partnerschaft gegen&uuml;ber Konkubinatspaaren in steuerlicher und sozialversicherungsrechtlicher Hinsicht beseitigen wollte. Die St&auml;nde haben mehrheitlich zugestimmt. Der Grund f&uuml;r das knappe Scheitern der&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_acf_changed":false,"authors":[{"ID":5,"display_name":"Wolfgang Maute","first_name":"Wolfgang","last_name":"Maute","description":"<p>Dr. iur. HSG, eidg. dipl. Steuerexperte, LL.M. (Int. Taxation), M Advice AG, Kreuzlingen<\/p>\n","image":"https:\/\/steuerportal.ch\/wp-content\/uploads\/2019\/11\/Maute_Wolfgang_neu-220x220.png","organiser_data":[],"url":"https:\/\/steuerportal.ch\/fr\/autoren\/wolfgang-maute\/"}],"related_sht_promodule":["<a href=\"https:\/\/steuerportal.ch\/fachmodule\/steuerrevue\/diverses\/\">Steuer Revue &#8594; Diverses<\/a>"],"pdf":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/shtpdf\/","language":"de"},"sht_proarticle_category":[20],"sht_proarticle_tag":[],"class_list":["post-873","sht_proarticle","type-sht_proarticle","status-publish","hentry","sht_proarticle_category-diverses"],"acf":{"authors":[5]},"shp_steuerportal_must_use":{"translations":[{"id":873,"link":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","title":{"rendered":"Familienbesteuerung vs. Zivilstandbesteuerung"},"language":"de"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch\" \/>\n<meta property=\"og:description\" content=\"Liebe Leserinnen und Leser Am 28. Februar 2016 hat das Schweizer Stimmvolk &auml;usserst knapp die Volksinitiative &laquo;F&uuml;r Ehe und Familie &ndash; gegen die Heiratsstrafe&raquo; abgelehnt, welche die Diskriminierung von verheirateten Paaren und Paaren in eingetragener Partnerschaft gegen&uuml;ber Konkubinatspaaren in steuerlicher und sozialversicherungsrechtlicher Hinsicht beseitigen wollte. Die St&auml;nde haben mehrheitlich zugestimmt. Der Grund f&uuml;r das knappe Scheitern der&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/\" \/>\n<meta property=\"og:site_name\" content=\"steuerportal.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-25T11:21:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/familienbesteuerung-vs-zivilstandbesteuerung\\\/\",\"url\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/familienbesteuerung-vs-zivilstandbesteuerung\\\/\",\"name\":\"Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#website\"},\"datePublished\":\"2019-06-01T14:18:00+00:00\",\"dateModified\":\"2019-11-25T11:21:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/familienbesteuerung-vs-zivilstandbesteuerung\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/familienbesteuerung-vs-zivilstandbesteuerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/familienbesteuerung-vs-zivilstandbesteuerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fachartikel\",\"item\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/articles-specialises\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Familienbesteuerung vs. Zivilstandbesteuerung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/\",\"name\":\"steuerportal.ch\",\"description\":\"Le portail suisse sp\u00e9cialis\u00e9 dans le domaine des imp\u00f4ts\",\"publisher\":{\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#organization\",\"name\":\"Steuerportal (Cosmos Verlag)\",\"url\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/steuerportal.ch\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cosmos_c-strich_h_positiv_bunt.svg\",\"contentUrl\":\"https:\\\/\\\/steuerportal.ch\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cosmos_c-strich_h_positiv_bunt.svg\",\"width\":191,\"height\":44,\"caption\":\"Steuerportal (Cosmos Verlag)\"},\"image\":{\"@id\":\"https:\\\/\\\/steuerportal.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","og_locale":"fr_FR","og_type":"article","og_title":"Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch","og_description":"Liebe Leserinnen und Leser Am 28. Februar 2016 hat das Schweizer Stimmvolk &auml;usserst knapp die Volksinitiative &laquo;F&uuml;r Ehe und Familie &ndash; gegen die Heiratsstrafe&raquo; abgelehnt, welche die Diskriminierung von verheirateten Paaren und Paaren in eingetragener Partnerschaft gegen&uuml;ber Konkubinatspaaren in steuerlicher und sozialversicherungsrechtlicher Hinsicht beseitigen wollte. Die St&auml;nde haben mehrheitlich zugestimmt. Der Grund f&uuml;r das knappe Scheitern der&hellip;","og_url":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","og_site_name":"steuerportal.ch","article_modified_time":"2019-11-25T11:21:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","url":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/","name":"Familienbesteuerung vs. Zivilstandbesteuerung &#8226; steuerportal.ch","isPartOf":{"@id":"https:\/\/steuerportal.ch\/fr\/#website"},"datePublished":"2019-06-01T14:18:00+00:00","dateModified":"2019-11-25T11:21:53+00:00","breadcrumb":{"@id":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/familienbesteuerung-vs-zivilstandbesteuerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/steuerportal.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Fachartikel","item":"https:\/\/steuerportal.ch\/fr\/articles-specialises\/"},{"@type":"ListItem","position":3,"name":"Familienbesteuerung vs. Zivilstandbesteuerung"}]},{"@type":"WebSite","@id":"https:\/\/steuerportal.ch\/fr\/#website","url":"https:\/\/steuerportal.ch\/fr\/","name":"steuerportal.ch","description":"Le portail suisse sp\u00e9cialis\u00e9 dans le domaine des imp\u00f4ts","publisher":{"@id":"https:\/\/steuerportal.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/steuerportal.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/steuerportal.ch\/fr\/#organization","name":"Steuerportal (Cosmos Verlag)","url":"https:\/\/steuerportal.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/steuerportal.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/steuerportal.ch\/wp-content\/uploads\/2021\/06\/cosmos_c-strich_h_positiv_bunt.svg","contentUrl":"https:\/\/steuerportal.ch\/wp-content\/uploads\/2021\/06\/cosmos_c-strich_h_positiv_bunt.svg","width":191,"height":44,"caption":"Steuerportal (Cosmos Verlag)"},"image":{"@id":"https:\/\/steuerportal.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/sht_proarticle\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/sht_proarticle"}],"about":[{"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/types\/sht_proarticle"}],"author":[{"embeddable":true,"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/sht_proarticle\/873\/revisions"}],"acf:user":[{"embeddable":true,"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"wp:attachment":[{"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/media?parent=873"}],"wp:term":[{"taxonomy":"sht_proarticle_category","embeddable":true,"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/sht_proarticle_category?post=873"},{"taxonomy":"sht_proarticle_tag","embeddable":true,"href":"https:\/\/steuerportal.ch\/fr\/wp-json\/wp\/v2\/sht_proarticle_tag?post=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}